{"id":321,"date":"2022-10-19T21:47:49","date_gmt":"2022-10-19T21:47:49","guid":{"rendered":"https:\/\/fundacionmfm.org\/?p=321"},"modified":"2022-10-19T21:47:51","modified_gmt":"2022-10-19T21:47:51","slug":"la-otra-busqueda-de-rafael-arraiz","status":"publish","type":"post","link":"https:\/\/fundacionmfm.org\/en\/que-leer\/la-otra-busqueda-de-rafael-arraiz\/","title":{"rendered":"La otra b\u00fasqueda de Rafael Arr\u00e1iz"},"content":{"rendered":"<p>Rafael Arr\u00e1iz Lucca abre un par\u00e9ntesis en su vida de historiador y ensayista para ofrecernos este nutrido recuento de sus experiencias psicol\u00f3gicas y espirituales.<\/p>\n\n\n\n<p><br>Sintiendo que ya ha cumplido con el mundo exterior y que el destino lo ha llevado al desaf\u00edo de la interioridad, el autor comparte en un lenguaje llano el proceso de desplazamientos internos que lo han hecho abrevar en fuentes tan universales como diversas de la psique y la espiritualidad.<\/p>\n\n\n\n<p><br>Desde la poes\u00eda; la lectura inici\u00e1tica a los fil\u00f3sofos cl\u00e1sicos; sus incursiones en el budismo, el tao\u00edsmo y el hinduismo; los atisbos comparativos entre la religiosidad oriental y la cultura judeocristiana; el psicoan\u00e1lisis y la psicolog\u00eda arquetipal; hasta el terreno m\u00e1s mundano del tarot, la astrolog\u00eda y otras vivencias esot\u00e9ricas, Arr\u00e1iz Lucca nos describe su \u00edntimo recorrido por el que ha buscado trascender lo concreto y hallar la serenidad que ans\u00edan una mente y un alma inquieta.<\/p>\n\n\n\n<p><br>Estas p\u00e1ginas contienen el honesto testimonio de un hombre que no ha cesado de indagar en el mundo de lo no evidente y no ha temido sumergirse en el r\u00edo subterr\u00e1neo que corre por debajo de nuestras vidas.<\/p>","protected":false},"excerpt":{"rendered":"<p>Rafael Arr\u00e1iz Lucca abre un par\u00e9ntesis en su vida de historiador y ensayista para ofrecernos este nutrido recuento de sus experiencias psicol\u00f3gicas y espirituales. Sintiendo que ya ha cumplido con el mundo exterior y que el destino lo ha llevado al desaf\u00edo de la interioridad, el autor comparte en un lenguaje llano el proceso de<br \/><a href=\"https:\/\/fundacionmfm.org\/en\/que-leer\/la-otra-busqueda-de-rafael-arraiz\/\" class=\"more\">Read more<\/a><\/p>","protected":false},"author":1,"featured_media":322,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-321","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-que-leer"],"_links":{"self":[{"href":"https:\/\/fundacionmfm.org\/en\/wp-json\/wp\/v2\/posts\/321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacionmfm.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacionmfm.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacionmfm.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacionmfm.org\/en\/wp-json\/wp\/v2\/comments?post=321"}],"version-history":[{"count":1,"href":"https:\/\/fundacionmfm.org\/en\/wp-json\/wp\/v2\/posts\/321\/revisions"}],"predecessor-version":[{"id":323,"href":"https:\/\/fundacionmfm.org\/en\/wp-json\/wp\/v2\/posts\/321\/revisions\/323"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundacionmfm.org\/en\/wp-json\/wp\/v2\/media\/322"}],"wp:attachment":[{"href":"https:\/\/fundacionmfm.org\/en\/wp-json\/wp\/v2\/media?parent=321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacionmfm.org\/en\/wp-json\/wp\/v2\/categories?post=321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacionmfm.org\/en\/wp-json\/wp\/v2\/tags?post=321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}